{"id":1419,"count":7,"description":"","link":"https:\/\/africafashionweek.com\/magazine\/tag\/fashion-designer\/","name":"fashion designer","slug":"fashion-designer","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/africafashionweek.com\/magazine\/wp-json\/wp\/v2\/tags\/1419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/africafashionweek.com\/magazine\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/africafashionweek.com\/magazine\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/africafashionweek.com\/magazine\/wp-json\/wp\/v2\/posts?tags=1419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}