{"id":2697,"count":1,"description":"","link":"https:\/\/africafashionweek.com\/magazine\/tag\/federal-republic-of-nigeria\/","name":"Federal Republic of Nigeria","slug":"federal-republic-of-nigeria","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/africafashionweek.com\/magazine\/wp-json\/wp\/v2\/tags\/2697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/africafashionweek.com\/magazine\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/africafashionweek.com\/magazine\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/africafashionweek.com\/magazine\/wp-json\/wp\/v2\/posts?tags=2697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}